{"id":12968,"date":"2020-12-30T21:46:59","date_gmt":"2020-12-30T21:46:59","guid":{"rendered":"http:\/\/demo.dentalvibe.com\/?p=12968"},"modified":"2021-05-10T23:51:12","modified_gmt":"2021-05-10T23:51:12","slug":"sedation-dentistry","status":"publish","type":"dentalvibe-patient","link":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/","title":{"rendered":"Sedierungszahnheilkunde: Was ist das und was erwartet Sie?"},"content":{"rendered":"<p>Viele Menschen haben Angst vor dem Gedanken an zahn\u00e4rztliche Eingriffe wie eine F\u00fcllung oder einen Wurzelkanal oder sogar eine routinem\u00e4\u00dfige Reinigung. Wenn du erlebst <a href=\"https:\/\/dentalvibe.com\/de\/dentalvibe-blog\/manage-dental-anxiety\/\">Zahnangst<\/a>, du bist nicht allein. Es ist jedoch wichtig, regelm\u00e4\u00dfig zum Zahnarzt zu gehen und die Mundgesundheit zu erhalten. Aus diesem Grund bieten viele Zahn\u00e4rzte Sedierungszahnheilkunde an, damit sich ihre Patienten wohler und weniger gestresst f\u00fchlen.<\/p>\n<h5><a href=\"https:\/\/dentalvibe.com\/de\/pain-free-dentists-find-a-dentist-near-you\/\">Haben Sie Probleme mit Zahnphobie? Suchen Sie sich einen Zahnarzt, der das DentalVibe Comfort Injection System verwendet.<\/a><\/h5>\n<p>Die Menschen f\u00fcrchten den Zahnarzt aus vielen Gr\u00fcnden. Erwachsene k\u00f6nnen aufgrund einer schlechten zahn\u00e4rztlichen Erfahrung in ihrer Kindheit starke Angst haben. Einige stellen m\u00f6glicherweise fest, dass sie bei topischen und injizierten An\u00e4sthetika, die bei der Zahnbehandlung verwendet werden, keine ausreichende Bet\u00e4ubung erfahren. Andere haben m\u00f6glicherweise eine geringe Schmerztoleranz, einen aktiven W\u00fcrgereflex oder sehr empfindliche Z\u00e4hne, was die Behandlung kompliziert macht. Wenn Sie den Zahnarzt aus einem dieser Gr\u00fcnde gemieden haben oder wenn eine erhebliche Menge an Korrekturarbeiten durchgef\u00fchrt werden muss, kann die zahn\u00e4rztliche Sedierung eine potenziell stressige Situation weitaus komfortabler machen.<\/p>\n<h2>Was ist Sedierungszahnheilkunde?<\/h2>\n<p>Sedierungszahnheilkunde bezieht sich auf die Praxis der Verwendung von Medikamenten, um Patienten zu helfen, sich w\u00e4hrend zahn\u00e4rztlicher Eingriffe zu entspannen.<\/p>\n<p>Es ist wichtig zu bedenken, dass zahn\u00e4rztliche Sedierung keine Schmerzbehandlung ist. Die zahn\u00e4rztliche Sedierung verwendet eine Vielzahl von Instrumenten, um den Patienten zu entspannen, und in einigen F\u00e4llen bleibt Ihnen \u00fcberhaupt keine Erinnerung an den Eingriff. Die Art der f\u00fcr Sie geeigneten zahn\u00e4rztlichen Sedierung wird durch die erforderlichen Mundpflegebehandlungen, Ihre allgemeine Gesundheit und andere Faktoren bestimmt.<\/p>\n<p>Die Sedierung kann durch ein inhaliertes Gas, eine einfache Pille oder ein Medikament erfolgen, das \u00fcber eine IV verabreicht wird. Die Sedierung wird im Allgemeinen in mehrere Kategorien unterteilt:<\/p>\n<p><strong>Leichte Beruhigung<\/strong>: Eine leichte zahn\u00e4rztliche Sedierung wird erreicht, wenn der Patient ein Gas namens Lachgas einatmet, das \u00fcblicherweise als Lachgas bezeichnet wird. Dies ist die leichteste Form der zahn\u00e4rztlichen Sedierung und bietet ein sehr sanftes und leichtes Ma\u00df an Entspannung. Der Patient ist wach, aber entspannt. Einige beschreiben diese milde Beruhigung als ein schwebendes Gef\u00fchl oder ein unbeschwertes Gef\u00fchl. Die Auswirkungen lassen schnell nach, nachdem das Lachgas vom Patienten entfernt wurde, und die Genesung erfolgt sehr schnell. Die Patienten k\u00f6nnen unmittelbar nach der Behandlung ihre normalen Aktivit\u00e4ten wieder aufnehmen.<\/p>\n<p><strong>M\u00e4\u00dfige Sedierung<\/strong>: Bei m\u00e4\u00dfiger Sedierung muss eine Pille wie Valium oder Halcion ein oder zwei Stunden vor einem geplanten Zahnarzttermin eingenommen werden. Diese Medikamente erzeugen ein starkes Gef\u00fchl der Entspannung. Einige Patienten berichten, dass diese Sedierungsstufe sie sehr benommen und entspannt genug macht, um w\u00e4hrend eines zahn\u00e4rztlichen Eingriffs einzuschlafen. Diese Art der Sedierung erm\u00f6glicht es jedoch auch, Patienten bei Bedarf leicht zu wecken.<\/p>\n<p><strong>Tiefe Beruhigung<\/strong>: Bei dieser Sedierungsstufe werden schmerzlindernde und beruhigende Medikamente \u00fcber eine Infusionsleitung verabreicht, wodurch der Patient w\u00e4hrend des zahn\u00e4rztlichen Eingriffs sehr entspannt ist. Die Patienten bleiben bei der Anwendung dieser Methode bei Bewusstsein und k\u00f6nnen mit dem Zahnarzt oder Arzt kommunizieren, sind jedoch \u00e4u\u00dferst ruhig und friedlich. Sie erinnern sich m\u00f6glicherweise nicht mehr an die anschlie\u00dfende Prozedur.<\/p>\n<p><strong>Vollnarkose<\/strong>: Manchmal verwenden Zahn\u00e4rzte eine Vollnarkose, was bedeutet, dass ein Patient v\u00f6llig bewusstlos ist und w\u00e4hrend der Behandlung nicht leicht geweckt werden kann. Dies wird bei zahn\u00e4rztlichen Eingriffen viel seltener angewendet als bei den oben aufgef\u00fchrten geringeren Sedierungswerten. Dieser Sedierungsgrad kann jedoch f\u00fcr gr\u00f6\u00dfere zahn\u00e4rztliche Eingriffe wie eine Zahnextraktion oder die Platzierung eines Zahnersatzes empfohlen werden <a href=\"https:\/\/dentalvibe.com\/de\/dentalvibe-blog\/dental-implants\/\">Zahnimplantat<\/a>.<\/p>\n<p>Wenn Sie dazu neigen, den Zahnarzt zu meiden oder <a href=\"https:\/\/dentalvibe.com\/de\/dentalvibe-blog\/postpone-dental-procedure\/\">zahn\u00e4rztliche Eingriffe verschieben<\/a>Vielleicht m\u00f6chten Sie fragen, ob Ihre Zahnarztpraxis Sedierungszahnheilkunde anbietet, oder eine finden, die dies tut. Es gibt viele Zahnarztpraxen, aus denen Sie ausw\u00e4hlen k\u00f6nnen, und Sie m\u00fcssen nicht weiter zu einer gehen, die Ihrem Komfort keine Priorit\u00e4t einr\u00e4umt. <a href=\"https:\/\/dentalvibe.com\/de\/pain-free-dentists-find-a-dentist-near-you\/\">Viele Zahnarztpraxen<\/a> sind mehr als gl\u00fccklich, die Bed\u00fcrfnisse ihrer Patienten zu erf\u00fcllen, damit sie die Zahnpflege erhalten, die sie ben\u00f6tigen. Die Sedierungszahnheilkunde ist nur eine Dienstleistung, die f\u00fcr \u00e4ngstliche Patienten einen gro\u00dfen Unterschied machen kann.<\/p>\n<p>Viele Zahn\u00e4rzte verwenden auch die <a href=\"https:\/\/dentalvibe.com\/de\/dentalvibe-blog\/what-is-dentalvibe\/\">DentalVibe Comfort Injection System<\/a> um die mit Zahninjektionen verbundenen Beschwerden zu beseitigen. DentalVibe verwendet ein leichtes Vibrationsgef\u00fchl, um Schmerzsignale vom Gehirn zu blockieren. Wenn ein Patient auf einen zahn\u00e4rztlichen Eingriff vorbereitet wird, f\u00fcr den eine orale Injektion erforderlich ist, wird das DentalVibe-Tool verwendet, um den Zahnfleischbereich und das die Injektionsstelle umgebende Gewebe sanft zu vibrieren. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/24773250\/\" target=\"_blank\" rel=\"noopener\">Nachforschungen haben ergeben<\/a> Wenn die Vibrations- und Injektionsempfindungen gleichzeitig auftreten, erreicht das Vibrationsgef\u00fchl zuerst das Gehirn und lenkt das Gehirn im Wesentlichen ab. Diese Ablenkung verhindert, dass das Gehirn das Gef\u00fchl der Injektion bemerkt.<\/p>\n<p>Lassen Sie sich nicht von Ihrer Angst und Furcht davon abhalten, sich um Ihre Mundgesundheit zu k\u00fcmmern. Sprechen Sie mit Ihrem Zahnarzt \u00fcber die f\u00fcr Sie geeignete Kombination aus Behandlungsoptionen, Sedierungsoptionen und schmerzlindernden Ma\u00dfnahmen. Sie werden in k\u00fcrzester Zeit l\u00e4cheln!<\/p>\n<h2>Finden Sie einen DentalVibe-Zahnarzt<\/h2>\n<p>Auf der Suche nach einem Zahnarzt, der anbietet <a href=\"https:\/\/dentalvibe.com\/de\/dentalvibe-blog\/pain-free-dentistry\/\">schmerzfreie Zahnheilkunde<\/a>? In unserem Verzeichnis zertifizierter schmerzfreier Zahn\u00e4rzte finden Sie zahlreiche Anbieter, die sich f\u00fcr eine m\u00f6glichst schmerzfreie Zahnheilkunde einsetzen! <a href=\"https:\/\/dentalvibe.com\/de\/pain-free-dentists-find-a-dentist-near-you\/\">Finden Sie einen DentalVibe-Zahnarzt und lassen Sie Zahnangst der Vergangenheit angeh\u00f6ren<\/a>!<\/p>","protected":false},"excerpt":{"rendered":"<p>Wenn Sie dazu neigen, den Zahnarzt zu meiden, oder wenn Sie eine erhebliche Menge an zahn\u00e4rztlicher Arbeit zu erledigen haben, kann die Sedierungszahnheilkunde Ihren Termin weitaus komfortabler machen.<\/p>","protected":false},"author":61,"featured_media":31610,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","blog-categories":[2415],"class_list":["post-12968","dentalvibe-patient","type-dentalvibe-patient","status-publish","format-standard","has-post-thumbnail","hentry","blog-categories-dental-solutions"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"If you tend to avoid the dentist or if you have a significant amount of dental work to be done, sedation dentistry can make your appointment far more comfortable.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dental Vibe\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Find A Dentist | DentalVibe | Anxiety-Free Dentists - Find a dentist that practices Anxiety-free-dentistry with DentalVibe near you!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sedation dentistry: What is it and what to expect - Find A Dentist | DentalVibe | Anxiety-Free Dentists\" \/>\n\t\t<meta property=\"og:description\" content=\"If you tend to avoid the dentist or if you have a significant amount of dental work to be done, sedation dentistry can make your appointment far more comfortable.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/demo.dentalvibe.com\/wp-content\/uploads\/2022\/03\/DentalVibe-logo-2.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/demo.dentalvibe.com\/wp-content\/uploads\/2022\/03\/DentalVibe-logo-2.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-30T21:46:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-05-10T23:51:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sedation dentistry: What is it and what to expect - Find A Dentist | DentalVibe | Anxiety-Free Dentists\" \/>\n\t\t<meta name=\"twitter:description\" content=\"If you tend to avoid the dentist or if you have a significant amount of dental work to be done, sedation dentistry can make your appointment far more comfortable.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/demo.dentalvibe.com\/wp-content\/uploads\/2022\/03\/DentalVibe-logo-2.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/#listItem\",\"name\":\"DentalVibe Patient Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/#listItem\",\"position\":2,\"name\":\"DentalVibe Patient Blog\",\"item\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/posts-for-patients\\\/#listItem\",\"name\":\"Posts For Patients\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/posts-for-patients\\\/#listItem\",\"position\":3,\"name\":\"Posts For Patients\",\"item\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/posts-for-patients\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/dental-solutions\\\/#listItem\",\"name\":\"Dental solutions\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/#listItem\",\"name\":\"DentalVibe Patient Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/dental-solutions\\\/#listItem\",\"position\":4,\"name\":\"Dental solutions\",\"item\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/dental-solutions\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#listItem\",\"name\":\"Sedation dentistry: What is it and what to expect\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/posts-for-patients\\\/#listItem\",\"name\":\"Posts For Patients\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#listItem\",\"position\":5,\"name\":\"Sedation dentistry: What is it and what to expect\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/blog-categories\\\/dental-solutions\\\/#listItem\",\"name\":\"Dental solutions\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/#organization\",\"name\":\"Find A Dentist | DentalVibe | Pain-Free Dentists\",\"description\":\"Find a dentist that practices Anxiety-free-dentistry with DentalVibe near you!\",\"url\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dentalvibe.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/DentalVibe-logo-with-tagline_blue.png\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#organizationLogo\",\"width\":1869,\"height\":617},\"image\":{\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/author\\\/dentalvibe123gmail-com\\\/#author\",\"url\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/author\\\/dentalvibe123gmail-com\\\/\",\"name\":\"Dental Vibe\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a58a0ec58a65a02f7fa3f5bbc91d74662d378acfadfef8008bfc56b95cebe1eb?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dental Vibe\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#webpage\",\"url\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/\",\"name\":\"Sedation dentistry: What is it and what to expect - Find A Dentist | DentalVibe | Anxiety-Free Dentists\",\"description\":\"If you tend to avoid the dentist or if you have a significant amount of dental work to be done, sedation dentistry can make your appointment far more comfortable.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/author\\\/dentalvibe123gmail-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/author\\\/dentalvibe123gmail-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dentalvibe.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sedation-dentistry.jpg\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#mainImage\",\"width\":560,\"height\":315,\"caption\":\"sedation dentistry\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/dentalvibe-patient\\\/sedation-dentistry\\\/#mainImage\"},\"datePublished\":\"2020-12-30T21:46:59-04:00\",\"dateModified\":\"2021-05-10T23:51:12-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/\",\"name\":\"Find A Dentist | DentalVibe | Anxiety-Free Dentists\",\"description\":\"Find a dentist that practices Anxiety-free-dentistry with DentalVibe near you!\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/dentalvibe.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sedation dentistry: What is it and what to expect - Find A Dentist | DentalVibe | Anxiety-Free Dentists","description":"Wenn Sie dazu neigen, den Zahnarzt zu meiden, oder wenn Sie eine erhebliche Menge an zahn\u00e4rztlicher Arbeit zu erledigen haben, kann die Sedierungszahnheilkunde Ihren Termin weitaus komfortabler machen.","canonical_url":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/dentalvibe.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/#listItem","name":"DentalVibe Patient Blog"}},{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/#listItem","position":2,"name":"DentalVibe Patient Blog","item":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/blog-categories\/posts-for-patients\/#listItem","name":"Posts For Patients"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/blog-categories\/posts-for-patients\/#listItem","position":3,"name":"Posts For Patients","item":"https:\/\/dentalvibe.com\/de\/blog-categories\/posts-for-patients\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/blog-categories\/dental-solutions\/#listItem","name":"Dental solutions"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/#listItem","name":"DentalVibe Patient Blog"}},{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/blog-categories\/dental-solutions\/#listItem","position":4,"name":"Dental solutions","item":"https:\/\/dentalvibe.com\/de\/blog-categories\/dental-solutions\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#listItem","name":"Sedation dentistry: What is it and what to expect"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/blog-categories\/posts-for-patients\/#listItem","name":"Posts For Patients"}},{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#listItem","position":5,"name":"Sedation dentistry: What is it and what to expect","previousItem":{"@type":"ListItem","@id":"https:\/\/dentalvibe.com\/de\/blog-categories\/dental-solutions\/#listItem","name":"Dental solutions"}}]},{"@type":"Organization","@id":"https:\/\/dentalvibe.com\/de\/#organization","name":"Find A Dentist | DentalVibe | Pain-Free Dentists","description":"Find a dentist that practices Anxiety-free-dentistry with DentalVibe near you!","url":"https:\/\/dentalvibe.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/dentalvibe.com\/wp-content\/uploads\/2023\/03\/DentalVibe-logo-with-tagline_blue.png","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#organizationLogo","width":1869,"height":617},"image":{"@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/dentalvibe.com\/de\/author\/dentalvibe123gmail-com\/#author","url":"https:\/\/dentalvibe.com\/de\/author\/dentalvibe123gmail-com\/","name":"Dental Vibe","image":{"@type":"ImageObject","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a58a0ec58a65a02f7fa3f5bbc91d74662d378acfadfef8008bfc56b95cebe1eb?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dental Vibe"}},{"@type":"WebPage","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#webpage","url":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/","name":"Sedation dentistry: What is it and what to expect - Find A Dentist | DentalVibe | Anxiety-Free Dentists","description":"If you tend to avoid the dentist or if you have a significant amount of dental work to be done, sedation dentistry can make your appointment far more comfortable.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/dentalvibe.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#breadcrumblist"},"author":{"@id":"https:\/\/dentalvibe.com\/de\/author\/dentalvibe123gmail-com\/#author"},"creator":{"@id":"https:\/\/dentalvibe.com\/de\/author\/dentalvibe123gmail-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/dentalvibe.com\/wp-content\/uploads\/2020\/12\/sedation-dentistry.jpg","@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#mainImage","width":560,"height":315,"caption":"sedation dentistry"},"primaryImageOfPage":{"@id":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/#mainImage"},"datePublished":"2020-12-30T21:46:59-04:00","dateModified":"2021-05-10T23:51:12-04:00"},{"@type":"WebSite","@id":"https:\/\/dentalvibe.com\/de\/#website","url":"https:\/\/dentalvibe.com\/de\/","name":"Find A Dentist | DentalVibe | Anxiety-Free Dentists","description":"Find a dentist that practices Anxiety-free-dentistry with DentalVibe near you!","inLanguage":"de-DE","publisher":{"@id":"https:\/\/dentalvibe.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Find A Dentist | DentalVibe | Anxiety-Free Dentists - Find a dentist that practices Anxiety-free-dentistry with DentalVibe near you!","og:type":"article","og:title":"Sedation dentistry: What is it and what to expect - Find A Dentist | DentalVibe | Anxiety-Free Dentists","og:description":"If you tend to avoid the dentist or if you have a significant amount of dental work to be done, sedation dentistry can make your appointment far more comfortable.","og:url":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/","og:image":"https:\/\/demo.dentalvibe.com\/wp-content\/uploads\/2022\/03\/DentalVibe-logo-2.png","og:image:secure_url":"https:\/\/demo.dentalvibe.com\/wp-content\/uploads\/2022\/03\/DentalVibe-logo-2.png","article:published_time":"2020-12-30T21:46:59+00:00","article:modified_time":"2021-05-10T23:51:12+00:00","twitter:card":"summary","twitter:title":"Sedation dentistry: What is it and what to expect - Find A Dentist | DentalVibe | Anxiety-Free Dentists","twitter:description":"If you tend to avoid the dentist or if you have a significant amount of dental work to be done, sedation dentistry can make your appointment far more comfortable.","twitter:image":"http:\/\/demo.dentalvibe.com\/wp-content\/uploads\/2022\/03\/DentalVibe-logo-2.png"},"aioseo_meta_data":{"post_id":"12968","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-04-18 03:36:50","updated":"2026-01-08 04:23:18","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dentalvibe.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/\" title=\"DentalVibe Patient Blog\">DentalVibe Patient Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dentalvibe.com\/de\/blog-categories\/posts-for-patients\/\" title=\"Posts For Patients\">Posts For Patients<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dentalvibe.com\/de\/blog-categories\/dental-solutions\/\" title=\"Dental solutions\">Dental solutions<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSedation dentistry: What is it and what to expect\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dentalvibe.com\/de\/"},{"label":"DentalVibe Patient Blog","link":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/"},{"label":"Posts For Patients","link":"https:\/\/dentalvibe.com\/de\/blog-categories\/posts-for-patients\/"},{"label":"Dental solutions","link":"https:\/\/dentalvibe.com\/de\/blog-categories\/dental-solutions\/"},{"label":"Sedation dentistry: What is it and what to expect","link":"https:\/\/dentalvibe.com\/de\/dentalvibe-patient\/sedation-dentistry\/"}],"_links":{"self":[{"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/dentalvibe-patient\/12968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/dentalvibe-patient"}],"about":[{"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/types\/dentalvibe-patient"}],"author":[{"embeddable":true,"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/comments?post=12968"}],"version-history":[{"count":0,"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/dentalvibe-patient\/12968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/media\/31610"}],"wp:attachment":[{"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/media?parent=12968"}],"wp:term":[{"taxonomy":"blog-categories","embeddable":true,"href":"https:\/\/dentalvibe.com\/de\/wp-json\/wp\/v2\/blog-categories?post=12968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}